{"id":15019,"date":"2026-01-12T12:53:05","date_gmt":"2026-01-12T10:53:05","guid":{"rendered":"https:\/\/www.lasonrisadesienna.es\/tienda\/?post_type=product&#038;p=15019"},"modified":"2026-05-08T12:38:20","modified_gmt":"2026-05-08T10:38:20","slug":"pack-10-neceser-sport-personalizado","status":"publish","type":"product","link":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/","title":{"rendered":"PACK 10 NECESER SPORT PERSONALIZADO"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>PACK 10 neceser multiusos en resistente poli\u00e9ster personalizados con inicial y nombre. Con cremallera, asa de transporte y ribete de refuerzo a juego. Medidas: 21.5 x 14 x 10 cm. Colores a elegir (beige, azul, rojo o naranja) <strong>Consultar stock por Whatsapp 619 917 528<\/strong>.<\/p>\n<p><strong>PRECIOS POR CANTIDAD:<\/strong><\/p>\n<ul>\n<li>De 10 a 20 unidades&#8230;&#8230;.4.25\u20ac\/ud<\/li>\n<li>De 21 a 30 unidades&#8230;&#8230;.3.25\u20ac\/ud<\/li>\n<li>De 31 a 49 unidades&#8230;&#8230;.2.75\u20ac\/ud<\/li>\n<li>+ de 50 unidades&#8230;&#8230;&#8230;&#8230;.2.25\u20ac\/ud<\/li>\n<\/ul>\n<p>Cada producto viene personalizado con su inicial y nombre (1 color para inicial y 1 color para nombre) envuelto en bolsita transparente y con pegatina personalizada del evento. <strong>Escr\u00edbenos un Whatsapp al 619917528 para realizar tu pedido.<\/strong><\/p>\n","protected":false},"featured_media":15174,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[784],"product_tag":[],"class_list":{"0":"post-15019","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-eventos","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PACK 10 NECESER SPORT PERSONALIZADO - La Sonrisa de Sienna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PACK 10 NECESER SPORT PERSONALIZADO - La Sonrisa de Sienna\" \/>\n<meta property=\"og:description\" content=\"PACK 10 neceser multiusos en resistente poli\u00e9ster personalizados con inicial y nombre. Con cremallera, asa de transporte y ribete de refuerzo a juego. Medidas: 21.5 x 14 x 10 cm. Colores a elegir (beige, azul, rojo o naranja) Consultar stock por Whatsapp 619 917 528.  PRECIOS POR CANTIDAD:   De 10 a 20 unidades.......4.25\u20ac\/ud  De 21 a 30 unidades.......3.25\u20ac\/ud  De 31 a 49 unidades.......2.75\u20ac\/ud  + de 50 unidades.............2.25\u20ac\/ud  Cada producto viene personalizado con su inicial y nombre (1 color para inicial y 1 color para nombre) envuelto en bolsita transparente y con pegatina personalizada del evento. Escr\u00edbenos un Whatsapp al 619917528 para realizar tu pedido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sonrisa de Sienna\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lasonrisadesienna\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T10:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-06-at-11.12.31.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1819\" \/>\n\t<meta property=\"og:image:height\" content=\"1819\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/\",\"url\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/\",\"name\":\"PACK 10 NECESER SPORT PERSONALIZADO - La Sonrisa de Sienna\",\"isPartOf\":{\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-06-at-11.12.31.jpeg\",\"datePublished\":\"2026-01-12T10:53:05+00:00\",\"dateModified\":\"2026-05-08T10:38:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#primaryimage\",\"url\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-06-at-11.12.31.jpeg\",\"contentUrl\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-06-at-11.12.31.jpeg\",\"width\":1819,\"height\":1819,\"caption\":\"NECESER IDEAL PARA REGALOS EN EVENTOS A LOS HOMBRES.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda2\",\"item\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/tienda2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PACK 10 NECESER SPORT PERSONALIZADO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/#website\",\"url\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/\",\"name\":\"La Sonrisa de Sienna\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/#organization\",\"name\":\"La Sonrisa de Sienna\",\"url\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2020\/01\/cropped-cropped-logo-sonrisa-alta-calidad-e1580066919446.png\",\"contentUrl\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2020\/01\/cropped-cropped-logo-sonrisa-alta-calidad-e1580066919446.png\",\"width\":512,\"height\":512,\"caption\":\"La Sonrisa de Sienna\"},\"image\":{\"@id\":\"https:\/\/www.lasonrisadesienna.es\/tienda\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lasonrisadesienna\/\",\"https:\/\/www.pinterest.es\/lasonrisadesienna\/\",\"https:\/\/www.instagram.com\/lasonrisadesienna\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PACK 10 NECESER SPORT PERSONALIZADO - La Sonrisa de Sienna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/","og_locale":"es_ES","og_type":"article","og_title":"PACK 10 NECESER SPORT PERSONALIZADO - La Sonrisa de Sienna","og_description":"PACK 10 neceser multiusos en resistente poli\u00e9ster personalizados con inicial y nombre. Con cremallera, asa de transporte y ribete de refuerzo a juego. Medidas: 21.5 x 14 x 10 cm. Colores a elegir (beige, azul, rojo o naranja) Consultar stock por Whatsapp 619 917 528.  PRECIOS POR CANTIDAD:   De 10 a 20 unidades.......4.25\u20ac\/ud  De 21 a 30 unidades.......3.25\u20ac\/ud  De 31 a 49 unidades.......2.75\u20ac\/ud  + de 50 unidades.............2.25\u20ac\/ud  Cada producto viene personalizado con su inicial y nombre (1 color para inicial y 1 color para nombre) envuelto en bolsita transparente y con pegatina personalizada del evento. Escr\u00edbenos un Whatsapp al 619917528 para realizar tu pedido.","og_url":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/","og_site_name":"La Sonrisa de Sienna","article_publisher":"https:\/\/www.facebook.com\/lasonrisadesienna\/","article_modified_time":"2026-05-08T10:38:20+00:00","og_image":[{"width":1819,"height":1819,"url":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-06-at-11.12.31.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/","url":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/","name":"PACK 10 NECESER SPORT PERSONALIZADO - La Sonrisa de Sienna","isPartOf":{"@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#primaryimage"},"image":{"@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-06-at-11.12.31.jpeg","datePublished":"2026-01-12T10:53:05+00:00","dateModified":"2026-05-08T10:38:20+00:00","breadcrumb":{"@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#primaryimage","url":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-06-at-11.12.31.jpeg","contentUrl":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-06-at-11.12.31.jpeg","width":1819,"height":1819,"caption":"NECESER IDEAL PARA REGALOS EN EVENTOS A LOS HOMBRES."},{"@type":"BreadcrumbList","@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/product\/pack-10-neceser-sport-personalizado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lasonrisadesienna.es\/tienda\/"},{"@type":"ListItem","position":2,"name":"Tienda2","item":"https:\/\/www.lasonrisadesienna.es\/tienda\/tienda2\/"},{"@type":"ListItem","position":3,"name":"PACK 10 NECESER SPORT PERSONALIZADO"}]},{"@type":"WebSite","@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/#website","url":"https:\/\/www.lasonrisadesienna.es\/tienda\/","name":"La Sonrisa de Sienna","description":"","publisher":{"@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lasonrisadesienna.es\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/#organization","name":"La Sonrisa de Sienna","url":"https:\/\/www.lasonrisadesienna.es\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2020\/01\/cropped-cropped-logo-sonrisa-alta-calidad-e1580066919446.png","contentUrl":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-content\/uploads\/2020\/01\/cropped-cropped-logo-sonrisa-alta-calidad-e1580066919446.png","width":512,"height":512,"caption":"La Sonrisa de Sienna"},"image":{"@id":"https:\/\/www.lasonrisadesienna.es\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lasonrisadesienna\/","https:\/\/www.pinterest.es\/lasonrisadesienna\/","https:\/\/www.instagram.com\/lasonrisadesienna\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/product\/15019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":6,"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/product\/15019\/revisions"}],"predecessor-version":[{"id":15260,"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/product\/15019\/revisions\/15260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/media\/15174"}],"wp:attachment":[{"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/media?parent=15019"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/product_brand?post=15019"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/product_cat?post=15019"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lasonrisadesienna.es\/tienda\/wp-json\/wp\/v2\/product_tag?post=15019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}